{"id":172,"count":4,"description":"","link":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/","name":"Storage Accessories","slug":"storage-accessories","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Storage Accessories archivos - Metrecubic<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storage Accessories archivos - Metrecubic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"Metrecubic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/\",\"url\":\"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/\",\"name\":\"Storage Accessories archivos - Metrecubic\",\"isPartOf\":{\"@id\":\"https:\/\/metre.emfasi.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/metre.emfasi.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storage Accessories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/metre.emfasi.es\/#website\",\"url\":\"https:\/\/metre.emfasi.es\/\",\"name\":\"Metrecubic\",\"description\":\"Alquiler de trasteros y minialmacenes privados.\",\"publisher\":{\"@id\":\"https:\/\/metre.emfasi.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/metre.emfasi.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/metre.emfasi.es\/#organization\",\"name\":\"METRECUBIC trasteros y mudanzas\",\"url\":\"https:\/\/metre.emfasi.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif\",\"contentUrl\":\"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif\",\"width\":118,\"height\":117,\"caption\":\"METRECUBIC trasteros y mudanzas\"},\"image\":{\"@id\":\"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storage Accessories archivos - Metrecubic","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Storage Accessories archivos - Metrecubic","og_url":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/","og_site_name":"Metrecubic","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/","url":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/","name":"Storage Accessories archivos - Metrecubic","isPartOf":{"@id":"https:\/\/metre.emfasi.es\/#website"},"breadcrumb":{"@id":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/metre.emfasi.es\/en\/categoria-producto\/storage-accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/metre.emfasi.es\/en\/"},{"@type":"ListItem","position":2,"name":"Storage Accessories"}]},{"@type":"WebSite","@id":"https:\/\/metre.emfasi.es\/#website","url":"https:\/\/metre.emfasi.es\/","name":"Metrecubic","description":"Alquiler de trasteros y minialmacenes privados.","publisher":{"@id":"https:\/\/metre.emfasi.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metre.emfasi.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/metre.emfasi.es\/#organization","name":"METRECUBIC trasteros y mudanzas","url":"https:\/\/metre.emfasi.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/","url":"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif","contentUrl":"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif","width":118,"height":117,"caption":"METRECUBIC trasteros y mudanzas"},"image":{"@id":"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/metre.emfasi.es\/en\/wp-json\/wp\/v2\/product_cat\/172"}],"collection":[{"href":"https:\/\/metre.emfasi.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/metre.emfasi.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/metre.emfasi.es\/en\/wp-json\/wp\/v2\/product?product_cat=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}