{"id":25660,"date":"2018-01-05T08:56:51","date_gmt":"2018-01-05T08:56:51","guid":{"rendered":"http:\/\/metre.emfasi.es\/producto\/papel-burbujas-kraft-150-metros\/"},"modified":"2023-02-06T12:30:44","modified_gmt":"2023-02-06T11:30:44","slug":"papier-bulle-kraft-150-metres","status":"publish","type":"product","link":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/","title":{"rendered":"Papier bulle + Kraft 150 m\u00e8tres"},"content":{"rendered":"<p>Rouleau de papier bulle et kraft pour prot\u00e9ger et emballer les objets rang\u00e9s dans le garde-meuble.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>80 cm x 150 m\u00a0\u00a0\u00a0 <strong>72,60 \u20ac\/u<\/strong><\/li>\n<\/ul>\n","protected":false},"featured_media":25661,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[144],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papier bulle + Kraft 150 m\u00e8tres - Metrecubic<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papier bulle + Kraft 150 m\u00e8tres - Metrecubic\" \/>\n<meta property=\"og:description\" content=\"80 cm x 150 m\u00a0\u00a0\u00a0 72,60 \u20ac\/u\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/\" \/>\n<meta property=\"og:site_name\" content=\"Metrecubic\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T11:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metre.emfasi.es\/wp-content\/uploads\/2018\/04\/metrecubic-carton-proteccion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/\",\"url\":\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/\",\"name\":\"Papier bulle + Kraft 150 m\u00e8tres - Metrecubic\",\"isPartOf\":{\"@id\":\"https:\/\/metre.emfasi.es\/#website\"},\"datePublished\":\"2018-01-05T08:56:51+00:00\",\"dateModified\":\"2023-02-06T11:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/metre.emfasi.es\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/metre.emfasi.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papier bulle + Kraft 150 m\u00e8tres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/metre.emfasi.es\/#website\",\"url\":\"https:\/\/metre.emfasi.es\/\",\"name\":\"Metrecubic\",\"description\":\"Alquiler de trasteros y minialmacenes privados.\",\"publisher\":{\"@id\":\"https:\/\/metre.emfasi.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/metre.emfasi.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/metre.emfasi.es\/#organization\",\"name\":\"METRECUBIC trasteros y mudanzas\",\"url\":\"https:\/\/metre.emfasi.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif\",\"contentUrl\":\"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif\",\"width\":118,\"height\":117,\"caption\":\"METRECUBIC trasteros y mudanzas\"},\"image\":{\"@id\":\"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papier bulle + Kraft 150 m\u00e8tres - Metrecubic","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Papier bulle + Kraft 150 m\u00e8tres - Metrecubic","og_description":"80 cm x 150 m\u00a0\u00a0\u00a0 72,60 \u20ac\/u","og_url":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/","og_site_name":"Metrecubic","article_modified_time":"2023-02-06T11:30:44+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/metre.emfasi.es\/wp-content\/uploads\/2018\/04\/metrecubic-carton-proteccion.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/","url":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/","name":"Papier bulle + Kraft 150 m\u00e8tres - Metrecubic","isPartOf":{"@id":"https:\/\/metre.emfasi.es\/#website"},"datePublished":"2018-01-05T08:56:51+00:00","dateModified":"2023-02-06T11:30:44+00:00","breadcrumb":{"@id":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/metre.emfasi.es\/fr\/producto\/papier-bulle-kraft-150-metres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/metre.emfasi.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/metre.emfasi.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Papier bulle + Kraft 150 m\u00e8tres"}]},{"@type":"WebSite","@id":"https:\/\/metre.emfasi.es\/#website","url":"https:\/\/metre.emfasi.es\/","name":"Metrecubic","description":"Alquiler de trasteros y minialmacenes privados.","publisher":{"@id":"https:\/\/metre.emfasi.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metre.emfasi.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/metre.emfasi.es\/#organization","name":"METRECUBIC trasteros y mudanzas","url":"https:\/\/metre.emfasi.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/","url":"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif","contentUrl":"http:\/\/metre.emfasi.es\/wp-content\/uploads\/2017\/09\/logo-capsalera.gif","width":118,"height":117,"caption":"METRECUBIC trasteros y mudanzas"},"image":{"@id":"https:\/\/metre.emfasi.es\/#\/schema\/logo\/image\/"}}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"_links":{"self":[{"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/product\/25660"}],"collection":[{"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/media\/25661"}],"wp:attachment":[{"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/media?parent=25660"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/product_cat?post=25660"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/metre.emfasi.es\/fr\/wp-json\/wp\/v2\/product_tag?post=25660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}